{"id":582,"date":"2022-10-08T12:37:05","date_gmt":"2022-10-08T12:37:05","guid":{"rendered":"https:\/\/eurolabinternacional.com\/?post_type=lajme&#038;p=582"},"modified":"2024-09-04T10:09:47","modified_gmt":"2024-09-04T10:09:47","slug":"sicilian-wine-tasting","status":"publish","type":"lajme","link":"https:\/\/eurolabinternacional.com\/en\/lajme\/sicilian-wine-tasting\/","title":{"rendered":"Sicilian Wine Tasting"},"content":{"rendered":"<figure class=\"wp-block-video\">\r\n<div style=\"width: 1276px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-582-1\" width=\"1276\" height=\"720\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SaveClip.App_4A420965EF64BFD858454C9EE5D3EAA9_video_dashinit.mp4?_=1\" \/><a href=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SaveClip.App_4A420965EF64BFD858454C9EE5D3EAA9_video_dashinit.mp4\">https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SaveClip.App_4A420965EF64BFD858454C9EE5D3EAA9_video_dashinit.mp4<\/a><\/video><\/div>\r\n<\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"wp-image-580\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-223-of-298-scaled.jpg\" alt=\"\" srcset=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-223-of-298-scaled.jpg 2560w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-223-of-298-300x200.jpg 300w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-223-of-298-768x512.jpg 768w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-223-of-298-1536x1024.jpg 1536w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-223-of-298-2048x1366.jpg 2048w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-223-of-298-18x12.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Shija e ver\u00ebs si\u00e7iliane e \u201cDuca Di Salaparuta\u201d vjen n\u00eb Shqip\u00ebri, fal\u00eb bashk\u00ebpunimit me \u201cEurolab\u201d. N\u00eb nj\u00eb ceremoni degustimi t\u00eb zhvilluar n\u00eb rezidenc\u00ebn e Ambasad\u00ebs Italiane n\u00eb Tiran\u00eb, u prezantuan etiketa nga tre kantina t\u00eb ndryshme siciliane; ver\u00eb e bardh\u00eb, e kuqe dhe Marsala.<br \/>Roberto Magnisi, drejtues i <strong>\u201cDuca Di Salaparuta\u201d<\/strong>, tha se vera ka forc\u00ebn t\u00eb tejkaloj\u00eb kufirin dhe t\u00eb flas\u00eb t\u00eb gjitha gjuh\u00ebt e bot\u00ebs, duke transmetuar kultur\u00ebn e vendit prodhues.<br \/>Gjat\u00eb degustimit, t\u00eb ftuarit shijuan <strong>Duca Nero, Lavico Bianco, Sentiero del Vento, Lavico Rosso, Passo delle Mule, Marsala Vergine Riserva 2008, Marsala Semisecco Superiore Riserva 2015, Duca Enrico<\/strong>, historin\u00eb e secil\u00ebs ver\u00eb t\u00eb treguar nga somelieri Roberto Magnisi, t\u00eb shoq\u00ebruar me ushqimin e rekomanduar p\u00ebr kombinimin m\u00eb t\u00eb mir\u00eb t\u00eb shijes.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Grupi Duca di Salaparuta zot\u00ebron tre marka historike t\u00eb ver\u00ebs q\u00eb p\u00ebrfaq\u00ebsojn\u00eb Si\u00e7ilin\u00eb dhe Italin\u00eb n\u00eb mbar\u00eb bot\u00ebn: Corvo dhe Duca di Salaparuta, e themeluar n\u00eb 1824 dhe Florio, e themeluar n\u00eb 1833. T\u00eb blera nga familja Reina dhe t\u00eb bashkuara n\u00eb nj\u00eb entitet t\u00eb vet\u00ebm, k\u00ebto kompani historike sot p\u00ebrb\u00ebjn\u00eb grupin m\u00eb t\u00eb madh privat t\u00eb prodhimit t\u00eb ver\u00ebs n\u00eb Si\u00e7ili.<br \/>K\u00ebto kompani p\u00ebrshkruajn\u00eb historin\u00eb dhe tok\u00ebn e ishullit p\u00ebrmes pronave t\u00eb tyre dhe bodrumeve historike t\u00eb ver\u00ebs, por mbi t\u00eb gjitha p\u00ebrmes ver\u00ebrave t\u00eb tyre. Tre marka t\u00eb r\u00ebnd\u00ebsishme, secila p\u00ebrfaq\u00ebson nj\u00eb zon\u00eb specifike, ve\u00e7orit\u00eb e saj dalluese, dhe nj\u00eb gam\u00eb t\u00eb plot\u00eb ver\u00ebrash t\u00eb p\u00ebrshtatshme p\u00ebr t\u00eb gjitha llojet e pjatave, nga ato m\u00eb klasike dhe t\u00eb p\u00ebrditshme me Corvo deri tek ato m\u00eb moderne me Duca di Salaparuta dhe ato m\u00eb origjinalet, ver\u00ebrat Florio.<br \/>Kompania Eurolab shton n\u00eb portofolin e saj t\u00eb markave premium edhe Duca Di Sallaparuta duke u b\u00ebr\u00eb k\u00ebshtu distributor zyrtar n\u00eb Shqip\u00ebri, Kosov\u00eb, Maqedoni e Veriut, Mali i Zi, Serbi, BiH, Kroaci dhe Slloveni. T\u00eb gjith\u00eb mund t\u00eb shijojn\u00eb ver\u00ebn e mrekullueshme t\u00eb Duca Di Sallaparuta me porosi direkte n\u00eb<strong> <a href=\"https:\/\/mapo.eurolab.com.al\/\">Mapo Cash &amp; Carry<\/a><\/strong>.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" class=\"wp-image-578\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-195-of-298-scaled.jpg\" alt=\"\" srcset=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-195-of-298-scaled.jpg 2560w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-195-of-298-300x200.jpg 300w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-195-of-298-768x512.jpg 768w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-195-of-298-1536x1024.jpg 1536w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-195-of-298-2048x1365.jpg 2048w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-195-of-298-18x12.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" class=\"wp-image-576\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/erb1111.jpg\" alt=\"\" srcset=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/erb1111.jpg 1280w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/erb1111-300x200.jpg 300w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/erb1111-768x512.jpg 768w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/erb1111-18x12.jpg 18w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"wp-image-579\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-207-of-298-scaled.jpg\" alt=\"\" srcset=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-207-of-298-scaled.jpg 2560w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-207-of-298-300x200.jpg 300w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-207-of-298-768x512.jpg 768w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-207-of-298-1536x1024.jpg 1536w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-207-of-298-2048x1366.jpg 2048w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-207-of-298-18x12.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" class=\"wp-image-577\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-163-of-298-scaled.jpg\" alt=\"\" srcset=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-163-of-298-scaled.jpg 2560w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-163-of-298-300x200.jpg 300w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-163-of-298-768x512.jpg 768w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-163-of-298-1536x1024.jpg 1536w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-163-of-298-2048x1365.jpg 2048w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-163-of-298-18x12.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"wp-image-581\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-256-of-298-scaled.jpg\" alt=\"\" srcset=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-256-of-298-scaled.jpg 2560w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-256-of-298-300x200.jpg 300w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-256-of-298-768x512.jpg 768w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-256-of-298-1536x1024.jpg 1536w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-256-of-298-2048x1365.jpg 2048w, https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-256-of-298-18x12.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-video\"><\/figure>","protected":false},"featured_media":575,"template":"","class_list":["post-582","lajme","type-lajme","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicilian Wine Tasting - Eurolab<\/title>\n<meta name=\"description\" content=\"Shija e ver\u00ebs si\u00e7iliane e \u201cDuca Di Salaparuta\u201d vjen n\u00eb Shqip\u00ebri, fal\u00eb bashk\u00ebpunimit me \u201cEurolab\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurolabinternacional.com\/en\/lajme\/sicilian-wine-tasting\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicilian Wine Tasting - Eurolab\" \/>\n<meta property=\"og:description\" content=\"Shija e ver\u00ebs si\u00e7iliane e \u201cDuca Di Salaparuta\u201d vjen n\u00eb Shqip\u00ebri, fal\u00eb bashk\u00ebpunimit me \u201cEurolab\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurolabinternacional.com\/en\/lajme\/sicilian-wine-tasting\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurolab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EurolabInternacionalGrup\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T10:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/\",\"name\":\"Sicilian Wine Tasting - Eurolab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg\",\"datePublished\":\"2022-10-08T12:37:05+00:00\",\"dateModified\":\"2024-09-04T10:09:47+00:00\",\"description\":\"Shija e ver\u00ebs si\u00e7iliane e \u201cDuca Di Salaparuta\u201d vjen n\u00eb Shqip\u00ebri, fal\u00eb bashk\u00ebpunimit me \u201cEurolab\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"sicilian wine tasting\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/sicilian-wine-tasting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eurolabinternacional.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicilian Wine Tasting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#website\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/\",\"name\":\"Eurolab Internacional Grup\",\"description\":\"EUROLAB INTERNATIONAL GROUP\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurolabinternacional.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#organization\",\"name\":\"Eurolab Internacional Grup\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo.png\",\"width\":170,\"height\":36,\"caption\":\"Eurolab Internacional Grup\"},\"image\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EurolabInternacionalGrup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/eurolab-internacional-grup\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicilian Wine Tasting - Eurolab","description":"Shija e ver\u00ebs si\u00e7iliane e \u201cDuca Di Salaparuta\u201d vjen n\u00eb Shqip\u00ebri, fal\u00eb bashk\u00ebpunimit me \u201cEurolab\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurolabinternacional.com\/en\/lajme\/sicilian-wine-tasting\/","og_locale":"en_US","og_type":"article","og_title":"Sicilian Wine Tasting - Eurolab","og_description":"Shija e ver\u00ebs si\u00e7iliane e \u201cDuca Di Salaparuta\u201d vjen n\u00eb Shqip\u00ebri, fal\u00eb bashk\u00ebpunimit me \u201cEurolab\u201d.","og_url":"https:\/\/eurolabinternacional.com\/en\/lajme\/sicilian-wine-tasting\/","og_site_name":"Eurolab","article_publisher":"https:\/\/www.facebook.com\/EurolabInternacionalGrup","article_modified_time":"2024-09-04T10:09:47+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/","url":"https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/","name":"Sicilian Wine Tasting - Eurolab","isPartOf":{"@id":"https:\/\/eurolabinternacional.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/#primaryimage"},"image":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/#primaryimage"},"thumbnailUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg","datePublished":"2022-10-08T12:37:05+00:00","dateModified":"2024-09-04T10:09:47+00:00","description":"Shija e ver\u00ebs si\u00e7iliane e \u201cDuca Di Salaparuta\u201d vjen n\u00eb Shqip\u00ebri, fal\u00eb bashk\u00ebpunimit me \u201cEurolab\u201d.","breadcrumb":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/#primaryimage","url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg","contentUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2022\/10\/SICILIAN-WINE-TASTING-7-of-298-scaled.jpg","width":2560,"height":1707,"caption":"sicilian wine tasting"},{"@type":"BreadcrumbList","@id":"https:\/\/eurolabinternacional.com\/lajme\/sicilian-wine-tasting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eurolabinternacional.com\/"},{"@type":"ListItem","position":2,"name":"Sicilian Wine Tasting"}]},{"@type":"WebSite","@id":"https:\/\/eurolabinternacional.com\/#website","url":"https:\/\/eurolabinternacional.com\/","name":"Eurolab Internacional Grup","description":"EUROLAB INTERNATIONAL GROUP","publisher":{"@id":"https:\/\/eurolabinternacional.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurolabinternacional.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eurolabinternacional.com\/#organization","name":"Eurolab Internacional Grup","url":"https:\/\/eurolabinternacional.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eurolabinternacional.com\/#\/schema\/logo\/image\/","url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/11\/logo.png","contentUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/11\/logo.png","width":170,"height":36,"caption":"Eurolab Internacional Grup"},"image":{"@id":"https:\/\/eurolabinternacional.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EurolabInternacionalGrup","https:\/\/www.linkedin.com\/company\/eurolab-internacional-grup\/"]}]}},"_links":{"self":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/lajme\/582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/lajme"}],"about":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/types\/lajme"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/media\/575"}],"wp:attachment":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/media?parent=582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}