{"id":1642,"date":"2024-12-30T01:01:12","date_gmt":"2024-12-30T01:01:12","guid":{"rendered":"https:\/\/eurolabinternacional.com\/?post_type=lajme&#038;p=1642"},"modified":"2025-02-05T14:44:32","modified_gmt":"2025-02-05T14:44:32","slug":"new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration","status":"publish","type":"lajme","link":"https:\/\/eurolabinternacional.com\/en\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/","title":{"rendered":"New Year\u2019s Red Party at Lime Lounge: An Evening of Elegance &amp; Celebration with Mo\u00ebt Chandon and Belvedere Vodka"},"content":{"rendered":"<div style=\"width: 720px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1642-1\" width=\"720\" height=\"1280\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Video-2025-01-28-at-4.22.22-PM-1.mp4?_=1\" \/><a href=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Video-2025-01-28-at-4.22.22-PM-1.mp4\">https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Video-2025-01-28-at-4.22.22-PM-1.mp4<\/a><\/video><\/div>","protected":false},"featured_media":1640,"template":"","class_list":["post-1642","lajme","type-lajme","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance &amp; Festimi me Moet Chandon dhe Belvedere Vodka - Eurolab<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurolabinternacional.com\/en\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance &amp; Festimi me Moet Chandon dhe Belvedere Vodka - Eurolab\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurolabinternacional.com\/en\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurolab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EurolabInternacionalGrup\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-05T14:44:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-01-015902.png\" \/>\n\t<meta property=\"og:image:width\" content=\"577\" \/>\n\t<meta property=\"og:image:height\" content=\"736\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/\",\"name\":\"New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance & Festimi me Moet Chandon dhe Belvedere Vodka - Eurolab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Screenshot-2025-02-01-015902.png\",\"datePublished\":\"2024-12-30T01:01:12+00:00\",\"dateModified\":\"2025-02-05T14:44:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Screenshot-2025-02-01-015902.png\",\"contentUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Screenshot-2025-02-01-015902.png\",\"width\":577,\"height\":736},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eurolabinternacional.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance &#038; Festimi me Moet Chandon dhe Belvedere Vodka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#website\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/\",\"name\":\"Eurolab Internacional Grup\",\"description\":\"EUROLAB INTERNATIONAL GROUP\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurolabinternacional.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#organization\",\"name\":\"Eurolab Internacional Grup\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo.png\",\"width\":170,\"height\":36,\"caption\":\"Eurolab Internacional Grup\"},\"image\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EurolabInternacionalGrup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/eurolab-internacional-grup\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance & Festimi me Moet Chandon dhe Belvedere Vodka - Eurolab","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurolabinternacional.com\/en\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/","og_locale":"en_US","og_type":"article","og_title":"New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance & Festimi me Moet Chandon dhe Belvedere Vodka - Eurolab","og_url":"https:\/\/eurolabinternacional.com\/en\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/","og_site_name":"Eurolab","article_publisher":"https:\/\/www.facebook.com\/EurolabInternacionalGrup","article_modified_time":"2025-02-05T14:44:32+00:00","og_image":[{"width":577,"height":736,"url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-01-015902.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/","url":"https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/","name":"New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance & Festimi me Moet Chandon dhe Belvedere Vodka - Eurolab","isPartOf":{"@id":"https:\/\/eurolabinternacional.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/#primaryimage"},"image":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/#primaryimage"},"thumbnailUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-01-015902.png","datePublished":"2024-12-30T01:01:12+00:00","dateModified":"2025-02-05T14:44:32+00:00","breadcrumb":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/#primaryimage","url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-01-015902.png","contentUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-01-015902.png","width":577,"height":736},{"@type":"BreadcrumbList","@id":"https:\/\/eurolabinternacional.com\/lajme\/new-years-red-party-at-lime-lounge-a-night-of-elegance-celebration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eurolabinternacional.com\/"},{"@type":"ListItem","position":2,"name":"New Year\u2019s Red Party n\u00eb Lime Lounge: Nj\u00eb Mbr\u00ebmje Elegance &#038; Festimi me Moet Chandon dhe Belvedere Vodka"}]},{"@type":"WebSite","@id":"https:\/\/eurolabinternacional.com\/#website","url":"https:\/\/eurolabinternacional.com\/","name":"Eurolab Internacional Grup","description":"EUROLAB INTERNATIONAL GROUP","publisher":{"@id":"https:\/\/eurolabinternacional.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurolabinternacional.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eurolabinternacional.com\/#organization","name":"Eurolab Internacional Grup","url":"https:\/\/eurolabinternacional.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eurolabinternacional.com\/#\/schema\/logo\/image\/","url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/11\/logo.png","contentUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/11\/logo.png","width":170,"height":36,"caption":"Eurolab Internacional Grup"},"image":{"@id":"https:\/\/eurolabinternacional.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EurolabInternacionalGrup","https:\/\/www.linkedin.com\/company\/eurolab-internacional-grup\/"]}]}},"_links":{"self":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/lajme\/1642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/lajme"}],"about":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/types\/lajme"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/media\/1640"}],"wp:attachment":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/media?parent=1642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}