{"id":1113,"date":"2024-08-03T11:47:27","date_gmt":"2024-08-03T11:47:27","guid":{"rendered":"https:\/\/eurolabinternacional.com\/?post_type=lajme&#038;p=1113"},"modified":"2024-08-16T08:36:33","modified_gmt":"2024-08-16T08:36:33","slug":"corona-sunsets-ne-pushime-on-top","status":"publish","type":"lajme","link":"https:\/\/eurolabinternacional.com\/en\/lajme\/corona-sunsets-ne-pushime-on-top\/","title":{"rendered":"Corona Sunsets n\u00eb Pushime On Top"},"content":{"rendered":"<hr \/>\r\n\r\nCorona Sunsets \u2728 Muzik\u00eb dhe magji n\u00eb per\u00ebndim \ud83e\udde1\u00a0@pushime_on_top\u00a0@topchannelalbania\r\n\r\n#topchannel\u00a0#pushimeontop\u00a0#enishehu\u00a0#leikraja\r\n\r\n<div style=\"width: 518px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1113-1\" width=\"518\" height=\"922\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_CA4373FD95338F06748A5E43D4010F8B_video_dashinit.mp4?_=1\" \/><a href=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_CA4373FD95338F06748A5E43D4010F8B_video_dashinit.mp4\">https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_CA4373FD95338F06748A5E43D4010F8B_video_dashinit.mp4<\/a><\/video><\/div>\r\n\r\n&nbsp;","protected":false},"featured_media":1114,"template":"","class_list":["post-1113","lajme","type-lajme","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corona Sunsets n\u00eb Pushime On Top - Eurolab<\/title>\n<meta name=\"description\" content=\"Corona Sunsets \u2728 Muzik\u00eb dhe magji n\u00eb per\u00ebndim \ud83e\udde1\u00a0@pushime_on_top\u00a0@topchannelalbania#topchannel\u00a0#pushimeontop\u00a0#enishehu\u00a0#leikraja\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurolabinternacional.com\/en\/lajme\/corona-sunsets-ne-pushime-on-top\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corona Sunsets n\u00eb Pushime On Top - Eurolab\" \/>\n<meta property=\"og:description\" content=\"Corona Sunsets \u2728 Muzik\u00eb dhe magji n\u00eb per\u00ebndim \ud83e\udde1\u00a0@pushime_on_top\u00a0@topchannelalbania#topchannel\u00a0#pushimeontop\u00a0#enishehu\u00a0#leikraja\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurolabinternacional.com\/en\/lajme\/corona-sunsets-ne-pushime-on-top\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurolab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EurolabInternacionalGrup\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-16T08:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"358\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/\",\"name\":\"Corona Sunsets n\u00eb Pushime On Top - Eurolab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg\",\"datePublished\":\"2024-08-03T11:47:27+00:00\",\"dateModified\":\"2024-08-16T08:36:33+00:00\",\"description\":\"Corona Sunsets \u2728 Muzik\u00eb dhe magji n\u00eb per\u00ebndim \ud83e\udde1\u00a0@pushime_on_top\u00a0@topchannelalbania#topchannel\u00a0#pushimeontop\u00a0#enishehu\u00a0#leikraja\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg\",\"contentUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg\",\"width\":517,\"height\":358},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/lajme\\\/corona-sunsets-ne-pushime-on-top\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eurolabinternacional.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corona Sunsets n\u00eb Pushime On Top\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#website\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/\",\"name\":\"Eurolab Internacional Grup\",\"description\":\"EUROLAB INTERNATIONAL GROUP\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurolabinternacional.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#organization\",\"name\":\"Eurolab Internacional Grup\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eurolabinternacional.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo.png\",\"width\":170,\"height\":36,\"caption\":\"Eurolab Internacional Grup\"},\"image\":{\"@id\":\"https:\\\/\\\/eurolabinternacional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EurolabInternacionalGrup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/eurolab-internacional-grup\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corona Sunsets n\u00eb Pushime On Top - Eurolab","description":"Corona Sunsets \u2728 Muzik\u00eb dhe magji n\u00eb per\u00ebndim \ud83e\udde1\u00a0@pushime_on_top\u00a0@topchannelalbania#topchannel\u00a0#pushimeontop\u00a0#enishehu\u00a0#leikraja","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurolabinternacional.com\/en\/lajme\/corona-sunsets-ne-pushime-on-top\/","og_locale":"en_US","og_type":"article","og_title":"Corona Sunsets n\u00eb Pushime On Top - Eurolab","og_description":"Corona Sunsets \u2728 Muzik\u00eb dhe magji n\u00eb per\u00ebndim \ud83e\udde1\u00a0@pushime_on_top\u00a0@topchannelalbania#topchannel\u00a0#pushimeontop\u00a0#enishehu\u00a0#leikraja","og_url":"https:\/\/eurolabinternacional.com\/en\/lajme\/corona-sunsets-ne-pushime-on-top\/","og_site_name":"Eurolab","article_publisher":"https:\/\/www.facebook.com\/EurolabInternacionalGrup","article_modified_time":"2024-08-16T08:36:33+00:00","og_image":[{"width":517,"height":358,"url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/","url":"https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/","name":"Corona Sunsets n\u00eb Pushime On Top - Eurolab","isPartOf":{"@id":"https:\/\/eurolabinternacional.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/#primaryimage"},"image":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/#primaryimage"},"thumbnailUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg","datePublished":"2024-08-03T11:47:27+00:00","dateModified":"2024-08-16T08:36:33+00:00","description":"Corona Sunsets \u2728 Muzik\u00eb dhe magji n\u00eb per\u00ebndim \ud83e\udde1\u00a0@pushime_on_top\u00a0@topchannelalbania#topchannel\u00a0#pushimeontop\u00a0#enishehu\u00a0#leikraja","breadcrumb":{"@id":"https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/#primaryimage","url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg","contentUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/08\/SaveInsta.App_454518834_381521885032522_362096895228041141_n-e1723463346363.jpg","width":517,"height":358},{"@type":"BreadcrumbList","@id":"https:\/\/eurolabinternacional.com\/lajme\/corona-sunsets-ne-pushime-on-top\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eurolabinternacional.com\/"},{"@type":"ListItem","position":2,"name":"Corona Sunsets n\u00eb Pushime On Top"}]},{"@type":"WebSite","@id":"https:\/\/eurolabinternacional.com\/#website","url":"https:\/\/eurolabinternacional.com\/","name":"Eurolab Internacional Grup","description":"EUROLAB INTERNATIONAL GROUP","publisher":{"@id":"https:\/\/eurolabinternacional.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurolabinternacional.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eurolabinternacional.com\/#organization","name":"Eurolab Internacional Grup","url":"https:\/\/eurolabinternacional.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eurolabinternacional.com\/#\/schema\/logo\/image\/","url":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/11\/logo.png","contentUrl":"https:\/\/eurolabinternacional.com\/wp-content\/uploads\/2024\/11\/logo.png","width":170,"height":36,"caption":"Eurolab Internacional Grup"},"image":{"@id":"https:\/\/eurolabinternacional.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EurolabInternacionalGrup","https:\/\/www.linkedin.com\/company\/eurolab-internacional-grup\/"]}]}},"_links":{"self":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/lajme\/1113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/lajme"}],"about":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/types\/lajme"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/media\/1114"}],"wp:attachment":[{"href":"https:\/\/eurolabinternacional.com\/en\/wp-json\/wp\/v2\/media?parent=1113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}